{"id":17719,"date":"2023-01-01T18:45:44","date_gmt":"2023-01-01T17:45:44","guid":{"rendered":"https:\/\/sinedjib.com\/?p=17719"},"modified":"2025-07-24T22:26:39","modified_gmt":"2025-07-24T20:26:39","slug":"le-groupe-franco-espagnol-des-amigos-de-durruti-levolution-de-la-democratie-francaise","status":"publish","type":"post","link":"https:\/\/sinedjib.com\/index.php\/2023\/01\/01\/le-groupe-franco-espagnol-des-amigos-de-durruti-levolution-de-la-democratie-francaise\/","title":{"rendered":"Le groupe franco-espagnol des \u00ab\u00a0Amigos de Durruti\u00a0\u00bb : L&rsquo;\u00e9volution de la d\u00e9mocratie fran\u00e7aise"},"content":{"rendered":"\n<p><strong>Texte du groupe franco-espagnol des \u00ab\u00a0Amigos de Durruti\u00a0\u00bb paru dans <em><a rel=\"noreferrer noopener\" href=\"http:\/\/archivesautonomies.org\/IMG\/pdf\/anarchismes\/entre-deux\/revision\/revision-n06.pdf\" target=\"_blank\">R\u00e9vision<\/a><\/em>, n\u00b0 6, 1er ao\u00fbt 1939, p. 4-5<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-drop-cap\">Les d\u00e9crets-lois marquent un pas vers la fascisation de la France. Les avantages ouvriers sont battus en br\u00e8che. Les unes apr\u00e8s les autres, les conventions collectives sont d\u00e9nonc\u00e9es. Dans les nouvelles conventions, le patronat, en harmonie avec les mesures gouvernementales, s&rsquo;efforce d&rsquo;an\u00e9antir les avantages offerts par ces conventions, et de n&rsquo;en conserver que la discipline anti-ouvri\u00e8re. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Les libert\u00e9s individuelles sont, elles aussi, rudement attaqu\u00e9es. Le droit de changer d&rsquo;usine est interdit aux ouvriers travaillant pour la d\u00e9fense nationale. La surveillance, le mouchardage redoublent. La cadence de travail s&rsquo;accentue, et les ouvriers n&rsquo;ont plus d&rsquo;autre arme l\u00e9gale que la protestation platonique dont le patronat se moque. Au personnel employ\u00e9s, aux fonctionnaires, la semaine de 45 heures est substitu\u00e9e \u00e0 celle de 40, <span style=\"text-decoration: underline;\">pour le m\u00eame traitement<\/span>. <\/p>\n\n\n\n<p>Enfin, les parades militaires, la pr\u00e9paration de la guerre, la propagande officielle pour le repeuplement et la d\u00e9fense de la race, les arrestations pr\u00e9ventives, les proc\u00e8s en espionnage qu&rsquo;on \u00e9chafaude \u00e0 tort et \u00e0 travers, la prorogation de la chambre, tous ces facteurs concourent \u00e0 acc\u00e9l\u00e9rer la marche de la France vers un fascisme \u00ab\u00a0non-sanglant\u00a0\u00bb, qui a pour cause les difficult\u00e9s qu&rsquo;\u00e9prouve le capital pour survivre \u00e0 la grande faillite de l&rsquo;apr\u00e8s-guerre, et \u00e0 la n\u00e9cessit\u00e9 o\u00f9 il se trouve de pr\u00e9parer le prochain massacre.<\/p>\n\n\n\n<p>La d\u00e9mocratie bourgeoise fran\u00e7aise n&rsquo;est d\u00e9j\u00e0 plus qu&rsquo;une survivance.<\/p>\n\n\n\n<p>Apr\u00e8s les camps \u00ab\u00a0d&rsquo;accueil\u00a0\u00bb pour les espagnols, voici les camps de concentration pour les \u00e9trangers ind\u00e9sirables (Rieucros). Nous n&rsquo;attendrons sans doute pas longtemps apr\u00e8s les camps pour tous les ind\u00e9sirables, \u00e9trangers ou fran\u00e7ais. <\/p>\n\n\n\n<p>Il faut donc en finir avec le bobard bourgeois de la DEMOCRATIE. La libert\u00e9 et le bien-\u00eatre relatif n&rsquo;ont jamais \u00e9t\u00e9 accord\u00e9s par la bourgeoisie au prol\u00e9tariat que comme une <span style=\"text-decoration: underline;\">tol\u00e9rance provisoire<\/span>. La d\u00e9mocratie bourgeoise fran\u00e7aise se pr\u00e9pare \u00e0 assassiner le prol\u00e9tariat de ce pays, comme la d\u00e9mocratie bourgeoise espagnole l&rsquo;a fait dans le sien.<\/p>\n\n\n\n<p>Il ne peut pas y avoir de d\u00e9mocratie dans un pays o\u00f9 deux classes adverses sont directement int\u00e9ress\u00e9es \u00e0 la possession du pouvoir. La classe bourgeoise s&rsquo;y accroche avec d&rsquo;autant plus de force qu&rsquo;elle se sent incapable de l&rsquo;assurer. La classe ouvri\u00e8re r\u00e9agit d&rsquo;autant plus directement qu&rsquo;elle a vu le pouvoir lui fr\u00f4ler le nez et lui \u00e9chapper. <\/p>\n\n\n\n<p>Il n&rsquo;y a plus de collaboration possible entr\u00e9 deux classes qui arrivent \u00e0 cette \u00e9tape de la lutte. Il faut que l&rsquo;une des classes assujettisse ou \u00e9crase l&rsquo;autre.<\/p>\n\n\n\n<p>L&rsquo;illusion dans la d\u00e9mocratie, \u00e0 travers la catastrophique exp\u00e9rience des FRONTS POPULAIRES FRANCAIS ET ESPAGNOL a emp\u00each\u00e9 le prol\u00e9tariat d&rsquo;\u00e9craser la bourgeoisie dans ces deux pays. <\/p>\n\n\n\n<p>Il faut pr\u00e9parer le prol\u00e9tariat, moralement et mat\u00e9riellement, \u00e0 cette nouvelle \u00e9tape de cette \u00ab\u00a0lutte finale\u00a0\u00bb qui ne peut se r\u00e9soudre que par l&rsquo;assujettissement du prol\u00e9tariat (dans la guerre imp\u00e9rialiste en premier lieu) ou par son triomphe. <\/p>\n\n\n\n<p>Pour cela, il est n\u00e9cessaire de rompre avec ceux qui ont particip\u00e9 aux compromis avec la bourgeoisie, c&rsquo;est-\u00e0-dire au sabotage des mouvements ouvriers espagnols et fran\u00e7ais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Texte du groupe franco-espagnol des \u00ab\u00a0Amigos de Durruti\u00a0\u00bb paru dans R\u00e9vision, n\u00b0 6, 1er ao\u00fbt 1939, p. 4-5 Les d\u00e9crets-lois marquent un pas vers la fascisation de la France. Les avantages ouvriers sont battus en br\u00e8che. Les unes apr\u00e8s les autres, les conventions collectives sont d\u00e9nonc\u00e9es. Dans les nouvelles conventions, le patronat, en harmonie avec [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[1891,5238,126,344,401,425,457,474,513,971,985,5237],"class_list":["post-17719","post","type-post","status-publish","format-standard","hentry","category-presse","tag-1891","tag-amigos-de-durruti","tag-anarchisme","tag-democratie","tag-espagne","tag-fascisme","tag-france","tag-front-populaire","tag-guerre","tag-proletariat","tag-racisme","tag-revision"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9lTYU-4BN","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2361,"url":"https:\/\/sinedjib.com\/index.php\/2016\/11\/16\/sail-mort\/","url_meta":{"origin":17719,"position":0},"title":"Notre vieux camarade Sa\u00efl Mohamed est mort","author":"Nedjib Sidi Moussa","date":"16\/11\/2016","format":false,"excerpt":"Article paru dans Le Libertaire, n\u00b0 358, 30 avril 1953 Venu d\u00e8s sa jeunesse aux id\u00e9es libertaires, Sa\u00efl Mohamed fut toujours un militant exemplaire. Agitateur, propagandiste, militant fraternel, il s'\u00e9tait fait une r\u00e8gle d'intransigeance, repoussant tout geste qui e\u00fbt pu avoir un caract\u00e8re mercantile, m\u00e9prisant ses int\u00e9r\u00eats personnels. Combattant de\u2026","rel":"","context":"Dans &quot;presse&quot;","block_context":{"text":"presse","link":"https:\/\/sinedjib.com\/index.php\/category\/presse\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sinedjib.com\/wp-content\/uploads\/2016\/11\/Le-Libertaire-30-avril-1953.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":16456,"url":"https:\/\/sinedjib.com\/index.php\/2022\/06\/27\/mourir-a-madrid\/","url_meta":{"origin":17719,"position":1},"title":"Un film de la \u00ab\u00a0gauche\u00a0\u00bb : Mourir \u00e0 Madrid","author":"SiNedjib","date":"27\/06\/2022","format":false,"excerpt":"Article paru dans Pouvoir ouvrier, n\u00b0 51, mai 1963, p. 11-12 D\u00e8s les premi\u00e8res minutes, la falsification historique transpara\u00eet : l'Espagne est pr\u00e9sent\u00e9e seulement comme un pays sous-d\u00e9velopp\u00e9. Il y a des seigneurs, des couvents, des paysans dans une mis\u00e8re semi-africaine. Il n'y a pas la bourgeoisie, il n'y a\u2026","rel":"","context":"Dans &quot;presse&quot;","block_context":{"text":"presse","link":"https:\/\/sinedjib.com\/index.php\/category\/presse\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/medias.unifrance.org\/medias\/241\/92\/220401\/format_page\/media.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4987,"url":"https:\/\/sinedjib.com\/index.php\/2019\/02\/01\/anars\/","url_meta":{"origin":17719,"position":2},"title":"Roman r\u00e9aliste \u2013 Anars d\u2019Espagne : les ann\u00e9es Paname","author":"SiNedjib","date":"01\/02\/2019","format":false,"excerpt":"Mon dernier article intitul\u00e9 \"Roman r\u00e9aliste \u2013 Anars d\u2019Espagne\u00a0: les ann\u00e9es Paname\" vient de para\u00eetre dans le mensuel de critique et d\u2019exp\u00e9rimentation sociales CQFD, n\u00b0 173 (f\u00e9vrier 2019). En voici la pr\u00e9sentation par la r\u00e9daction de CQFD : \"Dans D\u00e9dicaces \u2013 Un exil libertaire espagnol (1939-1975), Freddy Gomez raconte les\u2026","rel":"","context":"Dans &quot;publications&quot;","block_context":{"text":"publications","link":"https:\/\/sinedjib.com\/index.php\/category\/publications\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":26948,"url":"https:\/\/sinedjib.com\/index.php\/2025\/08\/09\/un-appel-de-messali-hadj-a-la-democratie-francaise\/","url_meta":{"origin":17719,"position":3},"title":"Un appel de Messali Hadj \u00e0 la d\u00e9mocratie fran\u00e7aise","author":"SiNedjib","date":"09\/08\/2025","format":false,"excerpt":"Appel de Messali Hadj paru dans La Commune, n\u00b0 4, juillet 1957 ; Demain, n\u00b0 82, 4 juillet 1957 ; La Voix du Peuple, n\u00b0 33, juillet 1957 Nous publions ci-apr\u00e8s l'appel lanc\u00e9 par Messali Hadj aux d\u00e9mocrates fran\u00e7ais. Cet appel a \u00e9t\u00e9 envoy\u00e9 \u00e0 notre confr\u00e8re Demain. Nous remercions\u2026","rel":"","context":"Dans &quot;presse&quot;","block_context":{"text":"presse","link":"https:\/\/sinedjib.com\/index.php\/category\/presse\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sinedjib.com\/wp-content\/uploads\/2025\/08\/La-Commune-1957.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/sinedjib.com\/wp-content\/uploads\/2025\/08\/La-Commune-1957.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/sinedjib.com\/wp-content\/uploads\/2025\/08\/La-Commune-1957.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/sinedjib.com\/wp-content\/uploads\/2025\/08\/La-Commune-1957.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7188,"url":"https:\/\/sinedjib.com\/index.php\/2020\/02\/26\/sail\/","url_meta":{"origin":17719,"position":4},"title":"Mohamed Sa\u00efl : L&rsquo;oppression en Alg\u00e9rie","author":"SiNedjib","date":"26\/02\/2020","format":false,"excerpt":"Article de Mohamed Sa\u00efl paru dans L'Eveil social, n\u00b0 26, f\u00e9vrier 1934 Mohamed Sa\u00efl (1894-1953) , militant anarchiste et anarcho-syndicaliste, en 1936 en Espagne (au premier rang, au milieu) avec des membres du Groupe international de la colonne Durruti. Lettre ouverte au ca\u00efd des Beni-Oughlis, Sidi-Aich (Constantine) : \u00ab Imposante\u2026","rel":"","context":"Dans &quot;presse&quot;","block_context":{"text":"presse","link":"https:\/\/sinedjib.com\/index.php\/category\/presse\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sinedjib.com\/wp-content\/uploads\/2020\/02\/LEveil-social-f%C3%A9vrier-1934.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":26022,"url":"https:\/\/sinedjib.com\/index.php\/2025\/04\/07\/koestler-2\/","url_meta":{"origin":17719,"position":5},"title":"Marcel Baufr\u00e8re : La Lie de la Terre, par Arthur K\u0153stler","author":"SiNedjib","date":"07\/04\/2025","format":false,"excerpt":"Article de Marcel Baufr\u00e8re paru dans La V\u00e9rit\u00e9, n\u00b0 155, 27 d\u00e9cembre 1946, p. 3 \u00ab Si quelqu'un criait la nuit dans notre baraque, nous savions qu'il avait r\u00eav\u00e9 \u00e0 la Gestapo. Et, reprenant conscience, il retrouvait avec gratitude l'odeur de la paille pourrie du Vernet. \u00bb Car nous vivions\u2026","rel":"","context":"Dans &quot;livres&quot;","block_context":{"text":"livres","link":"https:\/\/sinedjib.com\/index.php\/category\/livres\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/sinedjib.com\/wp-content\/uploads\/2023\/03\/Arthur-Koestler-La-lie-de-la-terre.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/posts\/17719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/comments?post=17719"}],"version-history":[{"count":2,"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/posts\/17719\/revisions"}],"predecessor-version":[{"id":26678,"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/posts\/17719\/revisions\/26678"}],"wp:attachment":[{"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/media?parent=17719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/categories?post=17719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sinedjib.com\/index.php\/wp-json\/wp\/v2\/tags?post=17719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}